{"id":1695,"count":1,"description":"","link":"https:\/\/sciences.ucf.edu\/news\/tag\/isel-bedgood\/","name":"Isel Bedgood","slug":"isel-bedgood","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Isel Bedgood Archives - College of Sciences News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sciences.ucf.edu\/news\/tag\/isel-bedgood\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Isel Bedgood Archives - College of Sciences News\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sciences.ucf.edu\/news\/tag\/isel-bedgood\/\" \/>\n<meta property=\"og:site_name\" content=\"College of Sciences News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/sciences.ucf.edu\\\/news\\\/tag\\\/isel-bedgood\\\/\",\"url\":\"https:\\\/\\\/sciences.ucf.edu\\\/news\\\/tag\\\/isel-bedgood\\\/\",\"name\":\"Isel Bedgood Archives - College of Sciences News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sciences.ucf.edu\\\/news\\\/#website\"},\"inLanguage\":\"en-US\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sciences.ucf.edu\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/sciences.ucf.edu\\\/news\\\/\",\"name\":\"College of Sciences News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sciences.ucf.edu\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Isel Bedgood Archives - College of Sciences News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sciences.ucf.edu\/news\/tag\/isel-bedgood\/","og_locale":"en_US","og_type":"article","og_title":"Isel Bedgood Archives - College of Sciences News","og_url":"https:\/\/sciences.ucf.edu\/news\/tag\/isel-bedgood\/","og_site_name":"College of Sciences News","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/sciences.ucf.edu\/news\/tag\/isel-bedgood\/","url":"https:\/\/sciences.ucf.edu\/news\/tag\/isel-bedgood\/","name":"Isel Bedgood Archives - College of Sciences News","isPartOf":{"@id":"https:\/\/sciences.ucf.edu\/news\/#website"},"inLanguage":"en-US"},{"@type":"WebSite","@id":"https:\/\/sciences.ucf.edu\/news\/#website","url":"https:\/\/sciences.ucf.edu\/news\/","name":"College of Sciences News","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sciences.ucf.edu\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/sciences.ucf.edu\/news\/wp-json\/wp\/v2\/tags\/1695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sciences.ucf.edu\/news\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/sciences.ucf.edu\/news\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/sciences.ucf.edu\/news\/wp-json\/wp\/v2\/posts?tags=1695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}